{"id":1539,"date":"2025-09-19T02:08:27","date_gmt":"2025-09-19T02:08:27","guid":{"rendered":"https:\/\/lifemassageandwellness.com\/Amesbury\/?page_id=1539"},"modified":"2025-10-28T22:29:02","modified_gmt":"2025-10-28T22:29:02","slug":"memberships","status":"publish","type":"page","link":"https:\/\/lifemassageandwellness.com\/Amesbury\/memberships\/","title":{"rendered":"Memberships"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1539\" class=\"elementor elementor-1539\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6170dc7 e-flex e-con-boxed e-con e-parent\" data-id=\"6170dc7\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4a2eda5 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"4a2eda5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Join Our Wellness Membership<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7efa30 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"a7efa30\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Looking for a self-care routine you\u2019ll enjoy and actually stick to? Our Massage and Wellness Membership Progra is designed with you in mind. It\u2019s a totally stress free way to get stress free. Start your path to personal wellness today with routine therapeutic massage and skincare*.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-532fcf5 e-flex e-con-boxed e-con e-parent\" data-id=\"532fcf5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5738167 elementor-widget elementor-widget-heading\" data-id=\"5738167\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Member's Special<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cae1192 elementor-widget elementor-widget-image\" data-id=\"cae1192\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"230\" height=\"18\" src=\"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/sec-shape-1.png\" class=\"attachment-medium size-medium wp-image-130\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-436423e e-flex e-con-boxed e-con e-parent\" data-id=\"436423e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-cf848b9 e-con-full e-flex e-con e-child\" data-id=\"cf848b9\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-39d3bb6 e-con-full table-wrapper e-flex e-con e-child\" data-id=\"39d3bb6\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3cc20b9 e-con-full tbl-row e-flex e-con e-child\" data-id=\"3cc20b9\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-1530c02 e-con-full e-flex e-con e-child\" data-id=\"1530c02\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-afc9e70 e-con-full e-flex e-con e-child\" data-id=\"afc9e70\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9027125 elementor-widget elementor-widget-heading\" data-id=\"9027125\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">60 Min<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3cd77a0 e-con-full e-flex e-con e-child\" data-id=\"3cd77a0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d34320f elementor-widget elementor-widget-heading\" data-id=\"d34320f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">90 Min<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b24206b e-con-full tbl-row e-flex e-con e-child\" data-id=\"b24206b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-d71ed96 e-con-full e-flex e-con e-child\" data-id=\"d71ed96\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cd9dc15 elementor-widget elementor-widget-heading\" data-id=\"cd9dc15\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Members Classic Massage\/Facial <\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8e965d2 e-con-full e-flex e-con e-child\" data-id=\"8e965d2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b97be5f elementor-widget elementor-widget-heading\" data-id=\"b97be5f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">$109<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-440e8ee e-con-full e-flex e-con e-child\" data-id=\"440e8ee\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ef41f8 elementor-widget elementor-widget-heading\" data-id=\"3ef41f8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">$189<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-20624cb e-con-full tbl-row e-flex e-con e-child\" data-id=\"20624cb\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-81b1a33 e-con-full e-flex e-con e-child\" data-id=\"81b1a33\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9ec5447 elementor-widget elementor-widget-heading\" data-id=\"9ec5447\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Non Members Classic Massage\/Facial <\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bb76334 e-con-full e-flex e-con e-child\" data-id=\"bb76334\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8dd4735 elementor-widget elementor-widget-heading\" data-id=\"8dd4735\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">$129<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-669482a e-con-full e-flex e-con e-child\" data-id=\"669482a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-60cc891 elementor-widget elementor-widget-heading\" data-id=\"60cc891\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">$209<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c703764 e-con-full tbl-row e-flex e-con e-child\" data-id=\"c703764\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-8ec5c3e e-con-full e-flex e-con e-child\" data-id=\"8ec5c3e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c20d40 elementor-widget elementor-widget-heading\" data-id=\"4c20d40\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Advanced Level Therapist<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7d79717 e-con-full e-flex e-con e-child\" data-id=\"7d79717\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-20657ff elementor-widget elementor-widget-heading\" data-id=\"20657ff\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">+$10<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bf2d6b8 e-con-full e-flex e-con e-child\" data-id=\"bf2d6b8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c74facb elementor-widget elementor-widget-heading\" data-id=\"c74facb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">+$15<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8f2f25e e-con-full tbl-row e-flex e-con e-child\" data-id=\"8f2f25e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-d961732 e-con-full e-flex e-con e-child\" data-id=\"d961732\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6b7b647 elementor-widget elementor-widget-heading\" data-id=\"6b7b647\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Master Level Therapist<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c435f6e e-con-full e-flex e-con e-child\" data-id=\"c435f6e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c8dc5ac elementor-widget elementor-widget-heading\" data-id=\"c8dc5ac\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">+$15<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9782df3 e-con-full e-flex e-con e-child\" data-id=\"9782df3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b34307d elementor-widget elementor-widget-heading\" data-id=\"b34307d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">+$20<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2f339a1 e-con-full tbl-row e-flex e-con e-child\" data-id=\"2f339a1\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-c34f62b e-con-full e-flex e-con e-child\" data-id=\"c34f62b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e696ac elementor-widget elementor-widget-heading\" data-id=\"8e696ac\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><b>Includes: Massage or Facial<\/b><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4faa640 e-con-full e-flex e-con e-child\" data-id=\"4faa640\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a38cc0c e-con-full e-flex e-con e-child\" data-id=\"a38cc0c\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0c1105 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c0c1105\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/lifemassageandwellness.com\/Amesbury\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00a0Call Us to Learn More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-607f4d4 e-flex e-con-boxed e-con e-parent\" data-id=\"607f4d4\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-56168af e-con-full e-flex e-con e-child\" data-id=\"56168af\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-22e0231 elementor-widget elementor-widget-heading\" data-id=\"22e0231\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Member Perks \n&amp; Benefits<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a827551 elementor-widget elementor-widget-image\" data-id=\"a827551\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"230\" height=\"18\" src=\"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/sec-shape-1.png\" class=\"attachment-medium size-medium wp-image-130\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53da505 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"53da505\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"22\" height=\"21\" viewBox=\"0 0 22 21\" fill=\"none\"><path d=\"M19.75 9.69513V10.5001C19.7489 12.387 19.1379 14.223 18.0082 15.7342C16.8784 17.2455 15.2904 18.351 13.4809 18.886C11.6715 19.421 9.7376 19.3568 7.96766 18.7029C6.19772 18.049 4.68657 16.8405 3.65959 15.2576C2.63261 13.6747 2.14482 11.8022 2.26897 9.9194C2.39312 8.03662 3.12256 6.24441 4.34849 4.81006C5.57443 3.37572 7.23119 2.37608 9.07167 1.96025C10.9121 1.54442 12.8377 1.73467 14.5613 2.50263\" stroke=\"#2F4878\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M19.75 3.5L11 12.2588L8.375 9.63375\" stroke=\"#2F4878\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Access to exlusive discounts and benefits<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"22\" height=\"21\" viewBox=\"0 0 22 21\" fill=\"none\"><path d=\"M19.75 9.69513V10.5001C19.7489 12.387 19.1379 14.223 18.0082 15.7342C16.8784 17.2455 15.2904 18.351 13.4809 18.886C11.6715 19.421 9.7376 19.3568 7.96766 18.7029C6.19772 18.049 4.68657 16.8405 3.65959 15.2576C2.63261 13.6747 2.14482 11.8022 2.26897 9.9194C2.39312 8.03662 3.12256 6.24441 4.34849 4.81006C5.57443 3.37572 7.23119 2.37608 9.07167 1.96025C10.9121 1.54442 12.8377 1.73467 14.5613 2.50263\" stroke=\"#2F4878\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M19.75 3.5L11 12.2588L8.375 9.63375\" stroke=\"#2F4878\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">10% off retail products<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"22\" height=\"21\" viewBox=\"0 0 22 21\" fill=\"none\"><path d=\"M19.75 9.69513V10.5001C19.7489 12.387 19.1379 14.223 18.0082 15.7342C16.8784 17.2455 15.2904 18.351 13.4809 18.886C11.6715 19.421 9.7376 19.3568 7.96766 18.7029C6.19772 18.049 4.68657 16.8405 3.65959 15.2576C2.63261 13.6747 2.14482 11.8022 2.26897 9.9194C2.39312 8.03662 3.12256 6.24441 4.34849 4.81006C5.57443 3.37572 7.23119 2.37608 9.07167 1.96025C10.9121 1.54442 12.8377 1.73467 14.5613 2.50263\" stroke=\"#2F4878\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M19.75 3.5L11 12.2588L8.375 9.63375\" stroke=\"#2F4878\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Monthly massage or facial included<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"22\" height=\"21\" viewBox=\"0 0 22 21\" fill=\"none\"><path d=\"M19.75 9.69513V10.5001C19.7489 12.387 19.1379 14.223 18.0082 15.7342C16.8784 17.2455 15.2904 18.351 13.4809 18.886C11.6715 19.421 9.7376 19.3568 7.96766 18.7029C6.19772 18.049 4.68657 16.8405 3.65959 15.2576C2.63261 13.6747 2.14482 11.8022 2.26897 9.9194C2.39312 8.03662 3.12256 6.24441 4.34849 4.81006C5.57443 3.37572 7.23119 2.37608 9.07167 1.96025C10.9121 1.54442 12.8377 1.73467 14.5613 2.50263\" stroke=\"#2F4878\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M19.75 3.5L11 12.2588L8.375 9.63375\" stroke=\"#2F4878\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">No long-term commitment<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"22\" height=\"21\" viewBox=\"0 0 22 21\" fill=\"none\"><path d=\"M19.75 9.69513V10.5001C19.7489 12.387 19.1379 14.223 18.0082 15.7342C16.8784 17.2455 15.2904 18.351 13.4809 18.886C11.6715 19.421 9.7376 19.3568 7.96766 18.7029C6.19772 18.049 4.68657 16.8405 3.65959 15.2576C2.63261 13.6747 2.14482 11.8022 2.26897 9.9194C2.39312 8.03662 3.12256 6.24441 4.34849 4.81006C5.57443 3.37572 7.23119 2.37608 9.07167 1.96025C10.9121 1.54442 12.8377 1.73467 14.5613 2.50263\" stroke=\"#2F4878\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M19.75 3.5L11 12.2588L8.375 9.63375\" stroke=\"#2F4878\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Easy online booking<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-00d7f66 e-con-full e-flex e-con e-child\" data-id=\"00d7f66\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de61661 elementor-widget elementor-widget-image\" data-id=\"de61661\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"710\" height=\"510\" src=\"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/Member-Perks-Benefit-imgs.webp\" class=\"attachment-full size-full wp-image-1554\" alt=\"\" srcset=\"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/Member-Perks-Benefit-imgs.webp 710w, https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/Member-Perks-Benefit-imgs-300x215.webp 300w\" sizes=\"(max-width: 710px) 100vw, 710px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d956de2 e-flex e-con-boxed e-con e-parent\" data-id=\"d956de2\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b07a4fb e-con-full e-flex e-con e-child\" data-id=\"b07a4fb\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e05a2df elementor-widget elementor-widget-image\" data-id=\"e05a2df\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"710\" height=\"510\" src=\"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/monthly-sub-img.webp\" class=\"attachment-full size-full wp-image-1553\" alt=\"\" srcset=\"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/monthly-sub-img.webp 710w, https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/monthly-sub-img-300x215.webp 300w\" sizes=\"(max-width: 710px) 100vw, 710px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c0392fc e-con-full e-flex e-con e-child\" data-id=\"c0392fc\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c07079b elementor-widget elementor-widget-heading\" data-id=\"c07079b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Monthly \nSubscription<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c215638 elementor-widget elementor-widget-image\" data-id=\"c215638\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"230\" height=\"18\" src=\"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/sec-shape-1.png\" class=\"attachment-medium size-medium wp-image-130\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ba999e elementor-widget elementor-widget-text-editor\" data-id=\"9ba999e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>We believe in relieving your stress, not adding to it.\u00a0Our Wellness Membership Program is specifically-designed to have zero hassle and obligation. Memberships are paid month-to-month, with no long-term commitment.<br \/>Try a different massage every month personalized just for you.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7335376 e-con-full e-flex e-con e-child\" data-id=\"7335376\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bbf8902 elementor-widget elementor-widget-image\" data-id=\"bbf8902\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"75\" height=\"75\" src=\"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/month-sub-ico-1.svg\" class=\"attachment-medium size-medium wp-image-1564\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb2d447 elementor-widget elementor-widget-image\" data-id=\"bb2d447\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"78\" height=\"78\" src=\"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/month-sub-ico-2.svg\" class=\"attachment-medium size-medium wp-image-1565\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e43a13a elementor-widget elementor-widget-image\" data-id=\"e43a13a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"80\" height=\"80\" src=\"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/month-sub-ico-3.svg\" class=\"attachment-medium size-medium wp-image-1566\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9336c3a e-flex e-con-boxed e-con e-parent\" data-id=\"9336c3a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fa4722e elementor-widget elementor-widget-heading\" data-id=\"fa4722e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">How It Works<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c832eb4 elementor-widget elementor-widget-image\" data-id=\"c832eb4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"230\" height=\"18\" src=\"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/sec-shape-1.png\" class=\"attachment-medium size-medium wp-image-130\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d7bb3d member-tabs e-n-tabs-mobile elementor-widget elementor-widget-n-tabs\" data-id=\"1d7bb3d\" data-element_type=\"widget\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"30915389\" aria-label=\"Tabs. Open items with Enter or Space, close with Escape and navigate using the Arrow keys.\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t<button id=\"e-n-tab-title-309153891\" class=\"e-n-tab-title\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-309153891\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"63\" height=\"65\" viewBox=\"0 0 63 65\" fill=\"none\"><g clip-path=\"url(#clip0_478_558)\"><path d=\"M54.0843 50.6134C59.619 43.4714 60.9853 33.7323 57.7201 24.3989C57.5464 23.8772 57.1643 23.6221 56.5738 23.6221C51.4096 23.7381 46.4308 25.0714 42.1466 27.483C40.0509 23.0772 36.7625 19.17 32.6636 16.2134C32.4668 16.0163 32.2005 15.9004 31.9342 15.9004C31.6563 15.9004 31.4016 16.0047 31.251 16.1671C26.9553 19.2627 23.748 23.0656 21.7101 27.4714C17.5302 25.0598 12.5629 23.7265 7.28301 23.6105C6.80828 23.6105 6.39144 23.8772 6.14829 24.3873C2.77887 33.825 4.11043 43.3323 9.74928 50.6134C4.99041 52.0859 2.58203 53.9989 2.58203 56.3062C2.58203 62.5207 20.1586 64.77 31.9805 64.77C46.5234 64.77 61.2632 61.8598 61.2632 56.3062C61.2516 53.3613 57.0253 51.5294 54.0843 50.6134ZM55.6475 26.0569C58.7737 35.912 56.3769 45.9062 49.3602 52.2482H40.7688C44.8792 45.4656 45.736 37.1294 43.0729 29.7207C46.9171 27.4482 51.1433 26.2192 55.6475 26.0569ZM31.8531 18.625C42.9919 27.1468 45.5392 41.1989 37.932 52.2482H25.7743C18.2365 41.4192 20.8417 27.054 31.8531 18.625ZM8.05878 26.0685C12.7945 26.3468 17.1249 27.5989 20.6333 29.7207C17.9239 37.1294 18.7807 45.4656 22.9375 52.2482H14.3576C7.28301 45.8482 4.8862 35.854 8.05878 26.0685ZM51.537 60.3758C46.3034 61.7091 39.333 62.4511 31.911 62.4511C24.489 62.4511 17.5186 61.7207 12.2966 60.3758C6.46091 58.8453 4.90936 57.1758 4.90936 56.4221C4.90936 55.5642 6.62302 54.0685 11.4398 52.654C11.7987 53.0482 12.1808 53.4076 12.5513 53.7555C12.7482 53.941 12.9566 54.1265 13.1419 54.312C13.3271 54.4975 13.6745 54.683 13.9408 54.683H49.9044C50.3328 54.683 50.5644 54.4511 50.6686 54.3468C51.317 53.8134 51.8728 53.2801 52.4054 52.654C57.5464 54.0569 58.9242 55.6801 58.9242 56.4221C58.9127 57.1062 57.3727 58.8105 51.537 60.3758Z\" fill=\"#846834\"><\/path><path d=\"M31.8541 24.4337C35.5593 27.3555 37.5972 31.3787 37.5972 35.7845C37.5972 36.3874 38.153 36.9439 38.7667 36.9439C39.3803 36.9439 39.9361 36.3874 39.9361 35.7845C39.9361 30.4859 37.2151 25.4424 32.5373 22.0106C32.3405 21.8135 32.0741 21.6975 31.7963 21.6975C31.5184 21.6975 31.2636 21.8019 31.1131 21.9642C26.3774 25.454 23.668 30.4859 23.668 35.7845C23.668 36.4106 24.2585 36.9439 24.9532 36.9439C25.5669 36.9439 26.1227 36.3874 26.1227 35.7845C26.1111 31.4366 28.1953 27.3207 31.8541 24.4337Z\" fill=\"#846834\"><\/path><path d=\"M52.3469 17.5817C55.0563 17.5817 57.2679 15.4019 57.2679 12.7121C57.2679 10.0222 55.0679 7.84253 52.3469 7.84253C49.6375 7.84253 47.4375 10.0222 47.4375 12.7121C47.4375 15.4019 49.6375 17.5817 52.3469 17.5817ZM52.3469 10.3933C53.7248 10.3933 54.8132 11.4599 54.8132 12.828C54.8132 14.1962 53.7363 15.2628 52.3469 15.2628C50.969 15.2628 49.8806 14.1962 49.8806 12.828C49.8806 11.4599 50.969 10.3933 52.3469 10.3933Z\" fill=\"#846834\"><\/path><path d=\"M10.3059 13.9874C13.988 13.9874 16.9753 11.0193 16.9753 7.37871C16.9753 3.73814 13.988 0.77002 10.3059 0.77002C6.6239 0.77002 3.625 3.73814 3.625 7.37871C3.625 11.0889 6.566 13.9874 10.3059 13.9874ZM10.3059 3.08886C12.7027 3.08886 14.648 5.0135 14.648 7.37871C14.648 9.79031 12.7375 11.6686 10.3059 11.6686C7.8744 11.6686 5.96391 9.79031 5.96391 7.37871C5.96391 4.97871 7.8744 3.08886 10.3059 3.08886Z\" fill=\"#846834\"><\/path><path d=\"M60.7903 6.68295C61.6239 6.68295 62.3071 6.01049 62.3071 5.1757C62.3071 4.34092 61.6239 3.66846 60.7903 3.66846C59.9566 3.66846 59.2734 4.34092 59.2734 5.1757C59.2734 6.01049 59.945 6.68295 60.7903 6.68295Z\" fill=\"#846834\"><\/path><path d=\"M41.8098 14.683C42.6435 14.683 43.3266 14.0105 43.3266 13.1757C43.3266 12.3409 42.6435 11.6685 41.8098 11.6685C40.9761 11.6685 40.293 12.3409 40.293 13.1757C40.293 14.0105 40.9761 14.683 41.8098 14.683Z\" fill=\"#846834\"><\/path><path d=\"M26.3528 5.29184C27.1864 5.29184 27.8696 4.61937 27.8696 3.78459C27.8696 2.94981 27.1864 2.27734 26.3528 2.27734C25.5191 2.27734 24.8359 2.94981 24.8359 3.78459C24.8359 4.61937 25.5075 5.29184 26.3528 5.29184Z\" fill=\"#846834\"><\/path><path d=\"M13.9414 16.7699C13.9414 17.6047 14.6246 18.2772 15.4582 18.2772C16.2919 18.2772 16.975 17.6047 16.975 16.7699C16.975 15.9352 16.2919 15.2627 15.4582 15.2627C14.6246 15.2627 13.9414 15.9352 13.9414 16.7699Z\" fill=\"#846834\"><\/path><path d=\"M3.03363 31.2629C3.03363 30.4281 2.35049 29.7556 1.51682 29.7556C0.683146 29.7556 0 30.4281 0 31.2629C0 32.0976 0.683146 32.7701 1.51682 32.7701C2.35049 32.7701 3.03363 32.0976 3.03363 31.2629Z\" fill=\"#846834\"><\/path><path d=\"M61.4817 37.7556C60.648 37.7556 59.9648 38.4281 59.9648 39.2629C59.9648 40.0976 60.648 40.7701 61.4817 40.7701C62.3153 40.7701 62.9985 40.0976 62.9985 39.2629C62.9985 38.4281 62.3269 37.7556 61.4817 37.7556Z\" fill=\"#846834\"><\/path><\/g><defs><clipPath id=\"clip0_478_558\"><rect width=\"63\" height=\"64\" fill=\"white\" transform=\"translate(0 0.77002)\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"63\" height=\"65\" viewBox=\"0 0 63 65\" fill=\"none\"><g clip-path=\"url(#clip0_478_558)\"><path d=\"M54.0843 50.6134C59.619 43.4714 60.9853 33.7323 57.7201 24.3989C57.5464 23.8772 57.1643 23.6221 56.5738 23.6221C51.4096 23.7381 46.4308 25.0714 42.1466 27.483C40.0509 23.0772 36.7625 19.17 32.6636 16.2134C32.4668 16.0163 32.2005 15.9004 31.9342 15.9004C31.6563 15.9004 31.4016 16.0047 31.251 16.1671C26.9553 19.2627 23.748 23.0656 21.7101 27.4714C17.5302 25.0598 12.5629 23.7265 7.28301 23.6105C6.80828 23.6105 6.39144 23.8772 6.14829 24.3873C2.77887 33.825 4.11043 43.3323 9.74928 50.6134C4.99041 52.0859 2.58203 53.9989 2.58203 56.3062C2.58203 62.5207 20.1586 64.77 31.9805 64.77C46.5234 64.77 61.2632 61.8598 61.2632 56.3062C61.2516 53.3613 57.0253 51.5294 54.0843 50.6134ZM55.6475 26.0569C58.7737 35.912 56.3769 45.9062 49.3602 52.2482H40.7688C44.8792 45.4656 45.736 37.1294 43.0729 29.7207C46.9171 27.4482 51.1433 26.2192 55.6475 26.0569ZM31.8531 18.625C42.9919 27.1468 45.5392 41.1989 37.932 52.2482H25.7743C18.2365 41.4192 20.8417 27.054 31.8531 18.625ZM8.05878 26.0685C12.7945 26.3468 17.1249 27.5989 20.6333 29.7207C17.9239 37.1294 18.7807 45.4656 22.9375 52.2482H14.3576C7.28301 45.8482 4.8862 35.854 8.05878 26.0685ZM51.537 60.3758C46.3034 61.7091 39.333 62.4511 31.911 62.4511C24.489 62.4511 17.5186 61.7207 12.2966 60.3758C6.46091 58.8453 4.90936 57.1758 4.90936 56.4221C4.90936 55.5642 6.62302 54.0685 11.4398 52.654C11.7987 53.0482 12.1808 53.4076 12.5513 53.7555C12.7482 53.941 12.9566 54.1265 13.1419 54.312C13.3271 54.4975 13.6745 54.683 13.9408 54.683H49.9044C50.3328 54.683 50.5644 54.4511 50.6686 54.3468C51.317 53.8134 51.8728 53.2801 52.4054 52.654C57.5464 54.0569 58.9242 55.6801 58.9242 56.4221C58.9127 57.1062 57.3727 58.8105 51.537 60.3758Z\" fill=\"#846834\"><\/path><path d=\"M31.8541 24.4337C35.5593 27.3555 37.5972 31.3787 37.5972 35.7845C37.5972 36.3874 38.153 36.9439 38.7667 36.9439C39.3803 36.9439 39.9361 36.3874 39.9361 35.7845C39.9361 30.4859 37.2151 25.4424 32.5373 22.0106C32.3405 21.8135 32.0741 21.6975 31.7963 21.6975C31.5184 21.6975 31.2636 21.8019 31.1131 21.9642C26.3774 25.454 23.668 30.4859 23.668 35.7845C23.668 36.4106 24.2585 36.9439 24.9532 36.9439C25.5669 36.9439 26.1227 36.3874 26.1227 35.7845C26.1111 31.4366 28.1953 27.3207 31.8541 24.4337Z\" fill=\"#846834\"><\/path><path d=\"M52.3469 17.5817C55.0563 17.5817 57.2679 15.4019 57.2679 12.7121C57.2679 10.0222 55.0679 7.84253 52.3469 7.84253C49.6375 7.84253 47.4375 10.0222 47.4375 12.7121C47.4375 15.4019 49.6375 17.5817 52.3469 17.5817ZM52.3469 10.3933C53.7248 10.3933 54.8132 11.4599 54.8132 12.828C54.8132 14.1962 53.7363 15.2628 52.3469 15.2628C50.969 15.2628 49.8806 14.1962 49.8806 12.828C49.8806 11.4599 50.969 10.3933 52.3469 10.3933Z\" fill=\"#846834\"><\/path><path d=\"M10.3059 13.9874C13.988 13.9874 16.9753 11.0193 16.9753 7.37871C16.9753 3.73814 13.988 0.77002 10.3059 0.77002C6.6239 0.77002 3.625 3.73814 3.625 7.37871C3.625 11.0889 6.566 13.9874 10.3059 13.9874ZM10.3059 3.08886C12.7027 3.08886 14.648 5.0135 14.648 7.37871C14.648 9.79031 12.7375 11.6686 10.3059 11.6686C7.8744 11.6686 5.96391 9.79031 5.96391 7.37871C5.96391 4.97871 7.8744 3.08886 10.3059 3.08886Z\" fill=\"#846834\"><\/path><path d=\"M60.7903 6.68295C61.6239 6.68295 62.3071 6.01049 62.3071 5.1757C62.3071 4.34092 61.6239 3.66846 60.7903 3.66846C59.9566 3.66846 59.2734 4.34092 59.2734 5.1757C59.2734 6.01049 59.945 6.68295 60.7903 6.68295Z\" fill=\"#846834\"><\/path><path d=\"M41.8098 14.683C42.6435 14.683 43.3266 14.0105 43.3266 13.1757C43.3266 12.3409 42.6435 11.6685 41.8098 11.6685C40.9761 11.6685 40.293 12.3409 40.293 13.1757C40.293 14.0105 40.9761 14.683 41.8098 14.683Z\" fill=\"#846834\"><\/path><path d=\"M26.3528 5.29184C27.1864 5.29184 27.8696 4.61937 27.8696 3.78459C27.8696 2.94981 27.1864 2.27734 26.3528 2.27734C25.5191 2.27734 24.8359 2.94981 24.8359 3.78459C24.8359 4.61937 25.5075 5.29184 26.3528 5.29184Z\" fill=\"#846834\"><\/path><path d=\"M13.9414 16.7699C13.9414 17.6047 14.6246 18.2772 15.4582 18.2772C16.2919 18.2772 16.975 17.6047 16.975 16.7699C16.975 15.9352 16.2919 15.2627 15.4582 15.2627C14.6246 15.2627 13.9414 15.9352 13.9414 16.7699Z\" fill=\"#846834\"><\/path><path d=\"M3.03363 31.2629C3.03363 30.4281 2.35049 29.7556 1.51682 29.7556C0.683146 29.7556 0 30.4281 0 31.2629C0 32.0976 0.683146 32.7701 1.51682 32.7701C2.35049 32.7701 3.03363 32.0976 3.03363 31.2629Z\" fill=\"#846834\"><\/path><path d=\"M61.4817 37.7556C60.648 37.7556 59.9648 38.4281 59.9648 39.2629C59.9648 40.0976 60.648 40.7701 61.4817 40.7701C62.3153 40.7701 62.9985 40.0976 62.9985 39.2629C62.9985 38.4281 62.3269 37.7556 61.4817 37.7556Z\" fill=\"#846834\"><\/path><\/g><defs><clipPath id=\"clip0_478_558\"><rect width=\"63\" height=\"64\" fill=\"white\" transform=\"translate(0 0.77002)\"><\/rect><\/clipPath><\/defs><\/svg>\t\t<\/span>\n\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tSign Up in Your <br> Wellness Space\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-309153892\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-309153892\" style=\"--n-tabs-title-order: 2;\">\n\t\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"63\" height=\"64\" viewBox=\"0 0 63 64\" fill=\"none\"><g clip-path=\"url(#clip0_475_523)\"><path d=\"M7.60726 6.52716C7.51282 4.80716 7.6275 3.17249 8.99697 1.92852C9.77503 1.22121 10.6813 0.814791 11.7269 0.778865C13.2313 0.72722 14.4366 1.3245 15.3766 2.5056C16.303 3.67098 16.2378 5.0609 16.2401 6.45531C17.749 6.45531 19.1634 6.45531 20.6813 6.45531C20.5801 4.66795 20.7218 2.97938 22.2239 1.7691C23.0649 1.09322 24.0206 0.733956 25.1 0.776619C26.5369 0.835 27.8277 1.39187 28.4731 2.65604C29.0465 3.781 29.2309 5.10581 29.6334 6.49797C30.0944 6.49797 30.8163 6.49797 31.5381 6.49797C32.2329 6.49797 32.9255 6.49797 33.7126 6.49797C33.5957 4.69489 33.7801 3.04675 35.2057 1.82973C36.004 1.14711 36.926 0.774374 37.9739 0.772128C39.4446 0.769883 40.6162 1.38288 41.5156 2.55275C42.4016 3.70466 42.3274 5.06763 42.3432 6.44857C43.8296 6.44857 45.2463 6.44857 46.7799 6.44857C46.7799 5.93212 46.7596 5.43588 46.7821 4.93964C46.8878 2.59317 48.7115 0.799073 51.0052 0.769883C53.3281 0.740692 55.2418 2.53254 55.3857 4.89024C55.4172 5.42017 55.3902 5.95233 55.3902 6.52492C55.7792 6.62372 56.1233 6.70904 56.4673 6.79661C60.2654 7.78011 62.9639 11.0966 62.9729 15.0104C63.0044 28.4246 63.0134 41.841 62.9684 55.2552C62.9526 60.0896 59.0466 63.7564 54.0635 63.7586C39.0241 63.7676 23.9869 63.7811 8.9475 63.7272C7.66798 63.7227 6.28502 63.4667 5.12693 62.9413C1.70889 61.3897 0.0223494 58.5942 0.0156032 54.8443C-0.000137783 42.6673 0.00660836 30.4859 0.0156032 18.3067C0.0156032 16.8494 -0.0653505 15.3719 0.141531 13.9393C0.701461 10.0637 3.41791 7.35348 7.25647 6.64168C7.33742 6.62596 7.41388 6.59003 7.60726 6.52716ZM2.36776 21.1224C2.36776 21.4705 2.36776 21.7736 2.36776 22.0745C2.36776 32.9356 2.36551 43.7968 2.36776 54.6579C2.36776 58.7558 5.00775 61.4032 9.10041 61.4032C24.0274 61.4054 38.9544 61.4054 53.8791 61.4032C57.9807 61.4032 60.6275 58.7648 60.6297 54.6759C60.632 43.7856 60.6297 32.8975 60.6297 22.0071C60.6297 21.713 60.6297 21.4166 60.6297 21.1224C41.1513 21.1224 21.8012 21.1224 2.36776 21.1224ZM2.29355 18.657C21.8394 18.657 41.2098 18.657 60.6072 18.657C60.6072 17.2513 60.6882 15.8996 60.587 14.5636C60.4566 12.8413 59.6583 11.4042 58.3135 10.3017C57.4838 9.62136 56.5573 9.14982 55.3925 9.01061C55.3925 9.53155 55.4104 9.97839 55.3902 10.423C55.2778 12.7919 53.4046 14.5927 51.0704 14.5927C48.7205 14.5927 46.8833 12.8099 46.7799 10.4162C46.7574 9.92 46.7776 9.42377 46.7776 8.91405C45.2395 8.91405 43.8251 8.91405 42.3252 8.91405C42.3252 9.35191 42.3297 9.73812 42.3252 10.1243C42.2825 12.7425 40.4587 14.613 37.9762 14.5927C35.5565 14.5725 33.7328 12.6617 33.7036 10.1154C33.6991 9.70893 33.7036 9.30476 33.7036 8.86465C32.2779 8.86465 30.9894 8.86465 29.7009 8.8669C29.5952 8.8669 29.4895 8.89609 29.2961 8.92303C29.2961 9.44397 29.3164 9.94246 29.2916 10.4387C29.1724 12.8054 27.2948 14.5995 24.9561 14.595C22.6152 14.5883 20.778 12.7852 20.6858 10.3938C20.6678 9.8998 20.6835 9.4058 20.6835 8.86241C19.8493 8.86241 19.1499 8.86241 18.4506 8.86241C17.7332 8.86241 17.0181 8.86241 16.2288 8.86241C16.2288 9.4305 16.2423 9.8751 16.2266 10.3197C16.1366 12.8144 14.2882 14.6197 11.8596 14.595C9.50743 14.5703 7.66348 12.6998 7.60502 10.2703C7.59602 9.86387 7.60277 9.45745 7.60277 9.03755C5.16066 9.3317 2.96142 11.3369 2.5634 13.8091C2.30704 15.3697 2.37451 16.9841 2.29355 18.657ZM13.8654 7.7105C13.8632 7.7105 13.8632 7.7105 13.8609 7.7105C13.8609 6.81458 13.8947 5.91865 13.8519 5.02497C13.798 3.90675 12.9592 3.12085 11.9023 3.12983C10.8949 3.13881 10.0111 3.91797 9.97966 4.97782C9.92569 6.76742 9.92794 8.55927 9.97516 10.3489C10.0044 11.4649 10.8746 12.2373 11.9405 12.2306C13.0087 12.2238 13.807 11.4514 13.8564 10.313C13.8947 9.44622 13.8654 8.57724 13.8654 7.7105ZM23.0402 7.6117C23.0402 8.50988 23.0132 9.40805 23.0469 10.3062C23.0897 11.4424 23.8992 12.2261 24.9673 12.2283C26.0332 12.2306 26.8922 11.4514 26.9215 10.3264C26.9665 8.55928 26.9687 6.78988 26.9192 5.02273C26.8877 3.91348 25.9905 3.11636 24.9426 3.13432C23.8812 3.15228 23.0852 3.94716 23.0447 5.08784C23.0155 5.92763 23.0402 6.77191 23.0402 7.6117ZM39.9618 7.67009C39.9618 6.82805 39.9843 5.98601 39.9573 5.14398C39.9191 3.94941 39.1208 3.13432 38.0279 3.13207C36.9485 3.12983 36.0917 3.96288 36.0693 5.13275C36.0378 6.84377 36.0333 8.55703 36.0715 10.268C36.0962 11.4402 36.9575 12.2463 38.0571 12.2283C39.1253 12.2126 39.9123 11.4267 39.955 10.2793C39.9843 9.41029 39.9595 8.53907 39.9618 7.67009ZM49.132 7.68356C49.1298 7.68356 49.1275 7.68356 49.1253 7.68356C49.1253 8.49416 49.1253 9.307 49.1253 10.1176C49.1253 10.1737 49.1275 10.2299 49.1298 10.286C49.2017 11.4289 49.9641 12.2103 51.0277 12.2306C52.1296 12.2508 52.9953 11.4604 53.0223 10.2927C53.065 8.55927 53.0628 6.82356 53.0223 5.09009C52.9953 3.93818 52.1026 3.11411 51.0299 3.13432C49.9753 3.15453 49.1815 3.94716 49.1365 5.0856C49.1051 5.94784 49.132 6.81682 49.132 7.68356Z\" fill=\"#846834\"><\/path><path d=\"M19.5749 32.5091C19.5749 33.3219 19.5974 34.1347 19.5682 34.9453C19.5074 36.6294 18.2617 37.9183 16.5729 37.9699C14.9223 38.0216 13.2673 38.0193 11.6167 37.9722C9.89868 37.9228 8.62366 36.5935 8.59668 34.878C8.57194 33.2815 8.57194 31.685 8.59668 30.0885C8.62141 28.3775 9.81773 27.0751 11.5155 27.0055C13.22 26.9359 14.9336 26.9381 16.6381 27.0033C18.3449 27.0684 19.5187 28.346 19.5682 30.0728C19.5951 30.8834 19.5749 31.6962 19.5749 32.5091ZM17.2205 32.4776C17.2205 31.7501 17.2115 31.0226 17.2227 30.2951C17.2317 29.6776 16.9596 29.3385 16.3323 29.3363C14.8211 29.3318 13.31 29.3273 11.7988 29.3407C11.2209 29.3452 10.9443 29.6708 10.9466 30.2524C10.9533 31.7366 10.9511 33.2186 10.9488 34.7028C10.9466 35.3316 11.2726 35.6257 11.882 35.628C13.337 35.6302 14.7919 35.6257 16.2468 35.6302C16.9012 35.6324 17.2317 35.3338 17.2227 34.6624C17.2115 33.9327 17.2205 33.2051 17.2205 32.4776Z\" fill=\"#846834\"><\/path><path d=\"M19.5699 48.7413C19.5699 49.5811 19.5991 50.4232 19.5631 51.2629C19.4934 52.8729 18.2634 54.1348 16.66 54.182C14.9533 54.2314 13.242 54.2314 11.5352 54.1842C9.89815 54.1393 8.63662 52.8415 8.60064 51.2023C8.56466 49.5497 8.56691 47.897 8.59839 46.2444C8.63212 44.5738 9.92289 43.2647 11.5937 43.2243C13.2442 43.1816 14.8993 43.1839 16.5498 43.2221C18.2364 43.2602 19.5002 44.5356 19.5631 46.222C19.5946 47.0617 19.5676 47.9038 19.5676 48.7436C19.5721 48.7413 19.5721 48.7413 19.5699 48.7413ZM17.2222 48.7121H17.22C17.22 47.9554 17.2222 47.201 17.22 46.4443C17.2177 45.8582 16.9141 45.5685 16.3362 45.5685C14.8543 45.5663 13.3702 45.5685 11.8883 45.5663C11.2744 45.5663 10.9505 45.8515 10.9505 46.4824C10.9528 47.9667 10.955 49.4486 10.9505 50.9329C10.9483 51.5661 11.2654 51.8468 11.8838 51.8468C13.3387 51.8423 14.7936 51.8355 16.2485 51.8512C16.9749 51.858 17.2492 51.5032 17.229 50.8116C17.2087 50.1133 17.2222 49.4127 17.2222 48.7121Z\" fill=\"#846834\"><\/path><path d=\"M48.9139 54.1977C48.0729 54.1977 47.2319 54.2246 46.3931 54.191C44.7403 54.1236 43.4788 52.8841 43.4383 51.236C43.3956 49.5564 43.3956 47.8746 43.4383 46.1927C43.4788 44.5536 44.7493 43.2714 46.3886 43.2265C48.0684 43.1794 49.7504 43.1794 51.4302 43.2265C53.0943 43.2714 54.3693 44.594 54.4008 46.2736C54.4323 47.897 54.4323 49.5227 54.4008 51.1484C54.3693 52.8729 53.0875 54.1393 51.3515 54.1977C50.5397 54.2246 49.728 54.2022 48.9139 54.2022C48.9139 54.1999 48.9139 54.1977 48.9139 54.1977ZM48.9297 45.5685C48.2011 45.5685 47.4747 45.5775 46.7484 45.5663C46.085 45.5573 45.7725 45.8649 45.777 46.5318C45.786 47.9868 45.7882 49.4419 45.777 50.8969C45.7725 51.5728 46.0963 51.8557 46.7574 51.849C48.1853 51.8377 49.611 51.8355 51.039 51.8512C51.7383 51.858 52.0689 51.5638 52.0599 50.8475C52.0419 49.4194 52.0441 47.9936 52.0599 46.5655C52.0666 45.8514 51.7271 45.5483 51.0322 45.564C50.3284 45.5797 49.629 45.5663 48.9297 45.5685Z\" fill=\"#846834\"><\/path><path d=\"M31.4987 26.9763C32.2835 26.9763 33.0683 26.9516 33.8508 26.9808C35.6656 27.0459 36.9271 28.236 36.999 30.0368C37.062 31.6603 37.0643 33.2882 36.999 34.9117C36.9271 36.7349 35.6048 37.9587 33.7699 37.9834C32.2565 38.0036 30.7454 38.0036 29.232 37.9834C27.3655 37.9587 26.0478 36.6945 25.9938 34.8286C25.9489 33.2613 25.9511 31.6895 25.9938 30.1222C26.0456 28.2787 27.3003 27.0504 29.1465 26.9808C29.9291 26.9516 30.7139 26.9763 31.4987 26.9763ZM31.5257 29.3318C30.7971 29.3318 30.0685 29.3385 29.3422 29.3295C28.69 29.3228 28.3437 29.6237 28.3437 30.2861C28.3415 31.7434 28.3392 33.1984 28.346 34.6557C28.3482 35.3046 28.6765 35.6324 29.3354 35.6302C30.7634 35.6257 32.1913 35.619 33.6192 35.6324C34.3186 35.6392 34.6604 35.3136 34.6626 34.622C34.6649 33.1939 34.6604 31.7658 34.6649 30.3377C34.6671 29.6371 34.3231 29.316 33.6282 29.3295C32.9244 29.3407 32.225 29.3295 31.5257 29.3318Z\" fill=\"#846834\"><\/path><path d=\"M31.4321 54.2044C30.6765 54.2044 29.9187 54.2179 29.1631 54.2021C27.3664 54.1595 26.0734 52.9582 26.0037 51.1663C25.9407 49.5429 25.943 47.9149 26.0014 46.2915C26.0667 44.4637 27.3799 43.24 29.2194 43.2153C30.7327 43.195 32.2439 43.1973 33.7573 43.2153C35.6394 43.2377 36.9482 44.4727 37.0089 46.3476C37.0584 47.9149 37.0561 49.4867 37.0112 51.054C36.9572 52.9402 35.6732 54.1685 33.7865 54.2044C32.9994 54.2156 32.2146 54.2044 31.4321 54.2044ZM31.4951 51.8467C32.2236 51.8467 32.95 51.8355 33.6786 51.8512C34.2947 51.8646 34.6478 51.5862 34.6545 50.9665C34.668 49.4553 34.6725 47.9419 34.65 46.4307C34.641 45.8694 34.3127 45.5685 33.7303 45.5685C32.2461 45.5707 30.762 45.5707 29.2778 45.5685C28.6482 45.5662 28.3469 45.903 28.3424 46.5026C28.3311 47.9868 28.3311 49.471 28.3424 50.9552C28.3469 51.5727 28.6864 51.8624 29.3071 51.8489C30.0401 51.8355 30.7665 51.8467 31.4951 51.8467Z\" fill=\"#846834\"><\/path><path d=\"M47.4785 33.9237C49.2437 32.1543 50.8786 30.4972 52.5426 28.8693C52.8259 28.5908 53.242 28.272 53.5883 28.2809C53.9615 28.2899 54.535 28.5886 54.6407 28.894C54.7756 29.2869 54.6856 29.9426 54.4203 30.2524C53.5658 31.2517 52.5853 32.1431 51.6544 33.0749C50.6245 34.1078 49.599 35.1452 48.5579 36.1669C47.8315 36.8787 47.2379 36.8877 46.5228 36.1894C45.5199 35.2081 44.5304 34.2134 43.5477 33.2142C42.8889 32.545 42.8282 31.8983 43.3454 31.3684C43.8468 30.8542 44.5574 30.9036 45.1916 31.5391C45.9404 32.2935 46.6645 33.0727 47.4785 33.9237Z\" fill=\"#846834\"><\/path><\/g><defs><clipPath id=\"clip0_475_523\"><rect width=\"63\" height=\"63\" fill=\"white\" transform=\"translate(0 0.77002)\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"63\" height=\"64\" viewBox=\"0 0 63 64\" fill=\"none\"><g clip-path=\"url(#clip0_475_523)\"><path d=\"M7.60726 6.52716C7.51282 4.80716 7.6275 3.17249 8.99697 1.92852C9.77503 1.22121 10.6813 0.814791 11.7269 0.778865C13.2313 0.72722 14.4366 1.3245 15.3766 2.5056C16.303 3.67098 16.2378 5.0609 16.2401 6.45531C17.749 6.45531 19.1634 6.45531 20.6813 6.45531C20.5801 4.66795 20.7218 2.97938 22.2239 1.7691C23.0649 1.09322 24.0206 0.733956 25.1 0.776619C26.5369 0.835 27.8277 1.39187 28.4731 2.65604C29.0465 3.781 29.2309 5.10581 29.6334 6.49797C30.0944 6.49797 30.8163 6.49797 31.5381 6.49797C32.2329 6.49797 32.9255 6.49797 33.7126 6.49797C33.5957 4.69489 33.7801 3.04675 35.2057 1.82973C36.004 1.14711 36.926 0.774374 37.9739 0.772128C39.4446 0.769883 40.6162 1.38288 41.5156 2.55275C42.4016 3.70466 42.3274 5.06763 42.3432 6.44857C43.8296 6.44857 45.2463 6.44857 46.7799 6.44857C46.7799 5.93212 46.7596 5.43588 46.7821 4.93964C46.8878 2.59317 48.7115 0.799073 51.0052 0.769883C53.3281 0.740692 55.2418 2.53254 55.3857 4.89024C55.4172 5.42017 55.3902 5.95233 55.3902 6.52492C55.7792 6.62372 56.1233 6.70904 56.4673 6.79661C60.2654 7.78011 62.9639 11.0966 62.9729 15.0104C63.0044 28.4246 63.0134 41.841 62.9684 55.2552C62.9526 60.0896 59.0466 63.7564 54.0635 63.7586C39.0241 63.7676 23.9869 63.7811 8.9475 63.7272C7.66798 63.7227 6.28502 63.4667 5.12693 62.9413C1.70889 61.3897 0.0223494 58.5942 0.0156032 54.8443C-0.000137783 42.6673 0.00660836 30.4859 0.0156032 18.3067C0.0156032 16.8494 -0.0653505 15.3719 0.141531 13.9393C0.701461 10.0637 3.41791 7.35348 7.25647 6.64168C7.33742 6.62596 7.41388 6.59003 7.60726 6.52716ZM2.36776 21.1224C2.36776 21.4705 2.36776 21.7736 2.36776 22.0745C2.36776 32.9356 2.36551 43.7968 2.36776 54.6579C2.36776 58.7558 5.00775 61.4032 9.10041 61.4032C24.0274 61.4054 38.9544 61.4054 53.8791 61.4032C57.9807 61.4032 60.6275 58.7648 60.6297 54.6759C60.632 43.7856 60.6297 32.8975 60.6297 22.0071C60.6297 21.713 60.6297 21.4166 60.6297 21.1224C41.1513 21.1224 21.8012 21.1224 2.36776 21.1224ZM2.29355 18.657C21.8394 18.657 41.2098 18.657 60.6072 18.657C60.6072 17.2513 60.6882 15.8996 60.587 14.5636C60.4566 12.8413 59.6583 11.4042 58.3135 10.3017C57.4838 9.62136 56.5573 9.14982 55.3925 9.01061C55.3925 9.53155 55.4104 9.97839 55.3902 10.423C55.2778 12.7919 53.4046 14.5927 51.0704 14.5927C48.7205 14.5927 46.8833 12.8099 46.7799 10.4162C46.7574 9.92 46.7776 9.42377 46.7776 8.91405C45.2395 8.91405 43.8251 8.91405 42.3252 8.91405C42.3252 9.35191 42.3297 9.73812 42.3252 10.1243C42.2825 12.7425 40.4587 14.613 37.9762 14.5927C35.5565 14.5725 33.7328 12.6617 33.7036 10.1154C33.6991 9.70893 33.7036 9.30476 33.7036 8.86465C32.2779 8.86465 30.9894 8.86465 29.7009 8.8669C29.5952 8.8669 29.4895 8.89609 29.2961 8.92303C29.2961 9.44397 29.3164 9.94246 29.2916 10.4387C29.1724 12.8054 27.2948 14.5995 24.9561 14.595C22.6152 14.5883 20.778 12.7852 20.6858 10.3938C20.6678 9.8998 20.6835 9.4058 20.6835 8.86241C19.8493 8.86241 19.1499 8.86241 18.4506 8.86241C17.7332 8.86241 17.0181 8.86241 16.2288 8.86241C16.2288 9.4305 16.2423 9.8751 16.2266 10.3197C16.1366 12.8144 14.2882 14.6197 11.8596 14.595C9.50743 14.5703 7.66348 12.6998 7.60502 10.2703C7.59602 9.86387 7.60277 9.45745 7.60277 9.03755C5.16066 9.3317 2.96142 11.3369 2.5634 13.8091C2.30704 15.3697 2.37451 16.9841 2.29355 18.657ZM13.8654 7.7105C13.8632 7.7105 13.8632 7.7105 13.8609 7.7105C13.8609 6.81458 13.8947 5.91865 13.8519 5.02497C13.798 3.90675 12.9592 3.12085 11.9023 3.12983C10.8949 3.13881 10.0111 3.91797 9.97966 4.97782C9.92569 6.76742 9.92794 8.55927 9.97516 10.3489C10.0044 11.4649 10.8746 12.2373 11.9405 12.2306C13.0087 12.2238 13.807 11.4514 13.8564 10.313C13.8947 9.44622 13.8654 8.57724 13.8654 7.7105ZM23.0402 7.6117C23.0402 8.50988 23.0132 9.40805 23.0469 10.3062C23.0897 11.4424 23.8992 12.2261 24.9673 12.2283C26.0332 12.2306 26.8922 11.4514 26.9215 10.3264C26.9665 8.55928 26.9687 6.78988 26.9192 5.02273C26.8877 3.91348 25.9905 3.11636 24.9426 3.13432C23.8812 3.15228 23.0852 3.94716 23.0447 5.08784C23.0155 5.92763 23.0402 6.77191 23.0402 7.6117ZM39.9618 7.67009C39.9618 6.82805 39.9843 5.98601 39.9573 5.14398C39.9191 3.94941 39.1208 3.13432 38.0279 3.13207C36.9485 3.12983 36.0917 3.96288 36.0693 5.13275C36.0378 6.84377 36.0333 8.55703 36.0715 10.268C36.0962 11.4402 36.9575 12.2463 38.0571 12.2283C39.1253 12.2126 39.9123 11.4267 39.955 10.2793C39.9843 9.41029 39.9595 8.53907 39.9618 7.67009ZM49.132 7.68356C49.1298 7.68356 49.1275 7.68356 49.1253 7.68356C49.1253 8.49416 49.1253 9.307 49.1253 10.1176C49.1253 10.1737 49.1275 10.2299 49.1298 10.286C49.2017 11.4289 49.9641 12.2103 51.0277 12.2306C52.1296 12.2508 52.9953 11.4604 53.0223 10.2927C53.065 8.55927 53.0628 6.82356 53.0223 5.09009C52.9953 3.93818 52.1026 3.11411 51.0299 3.13432C49.9753 3.15453 49.1815 3.94716 49.1365 5.0856C49.1051 5.94784 49.132 6.81682 49.132 7.68356Z\" fill=\"#846834\"><\/path><path d=\"M19.5749 32.5091C19.5749 33.3219 19.5974 34.1347 19.5682 34.9453C19.5074 36.6294 18.2617 37.9183 16.5729 37.9699C14.9223 38.0216 13.2673 38.0193 11.6167 37.9722C9.89868 37.9228 8.62366 36.5935 8.59668 34.878C8.57194 33.2815 8.57194 31.685 8.59668 30.0885C8.62141 28.3775 9.81773 27.0751 11.5155 27.0055C13.22 26.9359 14.9336 26.9381 16.6381 27.0033C18.3449 27.0684 19.5187 28.346 19.5682 30.0728C19.5951 30.8834 19.5749 31.6962 19.5749 32.5091ZM17.2205 32.4776C17.2205 31.7501 17.2115 31.0226 17.2227 30.2951C17.2317 29.6776 16.9596 29.3385 16.3323 29.3363C14.8211 29.3318 13.31 29.3273 11.7988 29.3407C11.2209 29.3452 10.9443 29.6708 10.9466 30.2524C10.9533 31.7366 10.9511 33.2186 10.9488 34.7028C10.9466 35.3316 11.2726 35.6257 11.882 35.628C13.337 35.6302 14.7919 35.6257 16.2468 35.6302C16.9012 35.6324 17.2317 35.3338 17.2227 34.6624C17.2115 33.9327 17.2205 33.2051 17.2205 32.4776Z\" fill=\"#846834\"><\/path><path d=\"M19.5699 48.7413C19.5699 49.5811 19.5991 50.4232 19.5631 51.2629C19.4934 52.8729 18.2634 54.1348 16.66 54.182C14.9533 54.2314 13.242 54.2314 11.5352 54.1842C9.89815 54.1393 8.63662 52.8415 8.60064 51.2023C8.56466 49.5497 8.56691 47.897 8.59839 46.2444C8.63212 44.5738 9.92289 43.2647 11.5937 43.2243C13.2442 43.1816 14.8993 43.1839 16.5498 43.2221C18.2364 43.2602 19.5002 44.5356 19.5631 46.222C19.5946 47.0617 19.5676 47.9038 19.5676 48.7436C19.5721 48.7413 19.5721 48.7413 19.5699 48.7413ZM17.2222 48.7121H17.22C17.22 47.9554 17.2222 47.201 17.22 46.4443C17.2177 45.8582 16.9141 45.5685 16.3362 45.5685C14.8543 45.5663 13.3702 45.5685 11.8883 45.5663C11.2744 45.5663 10.9505 45.8515 10.9505 46.4824C10.9528 47.9667 10.955 49.4486 10.9505 50.9329C10.9483 51.5661 11.2654 51.8468 11.8838 51.8468C13.3387 51.8423 14.7936 51.8355 16.2485 51.8512C16.9749 51.858 17.2492 51.5032 17.229 50.8116C17.2087 50.1133 17.2222 49.4127 17.2222 48.7121Z\" fill=\"#846834\"><\/path><path d=\"M48.9139 54.1977C48.0729 54.1977 47.2319 54.2246 46.3931 54.191C44.7403 54.1236 43.4788 52.8841 43.4383 51.236C43.3956 49.5564 43.3956 47.8746 43.4383 46.1927C43.4788 44.5536 44.7493 43.2714 46.3886 43.2265C48.0684 43.1794 49.7504 43.1794 51.4302 43.2265C53.0943 43.2714 54.3693 44.594 54.4008 46.2736C54.4323 47.897 54.4323 49.5227 54.4008 51.1484C54.3693 52.8729 53.0875 54.1393 51.3515 54.1977C50.5397 54.2246 49.728 54.2022 48.9139 54.2022C48.9139 54.1999 48.9139 54.1977 48.9139 54.1977ZM48.9297 45.5685C48.2011 45.5685 47.4747 45.5775 46.7484 45.5663C46.085 45.5573 45.7725 45.8649 45.777 46.5318C45.786 47.9868 45.7882 49.4419 45.777 50.8969C45.7725 51.5728 46.0963 51.8557 46.7574 51.849C48.1853 51.8377 49.611 51.8355 51.039 51.8512C51.7383 51.858 52.0689 51.5638 52.0599 50.8475C52.0419 49.4194 52.0441 47.9936 52.0599 46.5655C52.0666 45.8514 51.7271 45.5483 51.0322 45.564C50.3284 45.5797 49.629 45.5663 48.9297 45.5685Z\" fill=\"#846834\"><\/path><path d=\"M31.4987 26.9763C32.2835 26.9763 33.0683 26.9516 33.8508 26.9808C35.6656 27.0459 36.9271 28.236 36.999 30.0368C37.062 31.6603 37.0643 33.2882 36.999 34.9117C36.9271 36.7349 35.6048 37.9587 33.7699 37.9834C32.2565 38.0036 30.7454 38.0036 29.232 37.9834C27.3655 37.9587 26.0478 36.6945 25.9938 34.8286C25.9489 33.2613 25.9511 31.6895 25.9938 30.1222C26.0456 28.2787 27.3003 27.0504 29.1465 26.9808C29.9291 26.9516 30.7139 26.9763 31.4987 26.9763ZM31.5257 29.3318C30.7971 29.3318 30.0685 29.3385 29.3422 29.3295C28.69 29.3228 28.3437 29.6237 28.3437 30.2861C28.3415 31.7434 28.3392 33.1984 28.346 34.6557C28.3482 35.3046 28.6765 35.6324 29.3354 35.6302C30.7634 35.6257 32.1913 35.619 33.6192 35.6324C34.3186 35.6392 34.6604 35.3136 34.6626 34.622C34.6649 33.1939 34.6604 31.7658 34.6649 30.3377C34.6671 29.6371 34.3231 29.316 33.6282 29.3295C32.9244 29.3407 32.225 29.3295 31.5257 29.3318Z\" fill=\"#846834\"><\/path><path d=\"M31.4321 54.2044C30.6765 54.2044 29.9187 54.2179 29.1631 54.2021C27.3664 54.1595 26.0734 52.9582 26.0037 51.1663C25.9407 49.5429 25.943 47.9149 26.0014 46.2915C26.0667 44.4637 27.3799 43.24 29.2194 43.2153C30.7327 43.195 32.2439 43.1973 33.7573 43.2153C35.6394 43.2377 36.9482 44.4727 37.0089 46.3476C37.0584 47.9149 37.0561 49.4867 37.0112 51.054C36.9572 52.9402 35.6732 54.1685 33.7865 54.2044C32.9994 54.2156 32.2146 54.2044 31.4321 54.2044ZM31.4951 51.8467C32.2236 51.8467 32.95 51.8355 33.6786 51.8512C34.2947 51.8646 34.6478 51.5862 34.6545 50.9665C34.668 49.4553 34.6725 47.9419 34.65 46.4307C34.641 45.8694 34.3127 45.5685 33.7303 45.5685C32.2461 45.5707 30.762 45.5707 29.2778 45.5685C28.6482 45.5662 28.3469 45.903 28.3424 46.5026C28.3311 47.9868 28.3311 49.471 28.3424 50.9552C28.3469 51.5727 28.6864 51.8624 29.3071 51.8489C30.0401 51.8355 30.7665 51.8467 31.4951 51.8467Z\" fill=\"#846834\"><\/path><path d=\"M47.4785 33.9237C49.2437 32.1543 50.8786 30.4972 52.5426 28.8693C52.8259 28.5908 53.242 28.272 53.5883 28.2809C53.9615 28.2899 54.535 28.5886 54.6407 28.894C54.7756 29.2869 54.6856 29.9426 54.4203 30.2524C53.5658 31.2517 52.5853 32.1431 51.6544 33.0749C50.6245 34.1078 49.599 35.1452 48.5579 36.1669C47.8315 36.8787 47.2379 36.8877 46.5228 36.1894C45.5199 35.2081 44.5304 34.2134 43.5477 33.2142C42.8889 32.545 42.8282 31.8983 43.3454 31.3684C43.8468 30.8542 44.5574 30.9036 45.1916 31.5391C45.9404 32.2935 46.6645 33.0727 47.4785 33.9237Z\" fill=\"#846834\"><\/path><\/g><defs><clipPath id=\"clip0_475_523\"><rect width=\"63\" height=\"63\" fill=\"white\" transform=\"translate(0 0.77002)\"><\/rect><\/clipPath><\/defs><\/svg>\t\t<\/span>\n\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tBook Your Session\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-309153893\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-309153893\" style=\"--n-tabs-title-order: 3;\">\n\t\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"59\" height=\"59\" viewBox=\"0 0 59 59\" fill=\"none\"><g clip-path=\"url(#clip0_478_550)\"><path d=\"M2.37017 24.47C2.37017 22.07 3.58017 19.67 5.61017 18.17C6.62017 17.47 7.84017 16.87 9.15017 16.77C10.4602 16.67 11.6802 16.57 12.9902 16.17C17.7402 14.67 21.0802 10.17 21.0802 5.27002V1.97002C21.0802 0.37002 18.5502 0.37002 18.5502 1.97002V5.27002C18.5502 9.87002 14.8102 13.87 10.1502 14.27C8.84017 14.37 7.62017 14.47 6.31017 14.97C5.10017 15.47 3.98017 16.27 3.07017 17.17C1.25017 19.07 -0.269826 22.07 0.0301736 24.77L3.87017 57.17C4.07017 58.77 6.60017 58.47 6.40017 56.87L2.37017 24.47Z\" fill=\"#846834\"><\/path><path d=\"M56.0792 18.37C54.8692 16.77 53.1492 15.47 51.2192 14.77C49.2992 14.07 47.2692 14.37 45.3492 13.67C41.9092 12.37 39.4792 8.97002 39.4792 5.27002V1.97002C39.4792 0.37002 36.9492 0.37002 36.9492 1.97002V5.27002C36.9492 10.07 40.1892 14.57 44.7392 16.17C45.8492 16.57 47.0692 16.77 48.2792 16.77C49.6992 16.77 50.9092 17.27 52.0192 18.07C54.1392 19.57 55.3592 21.97 55.3592 24.47L51.7292 56.77C51.5292 58.37 54.0592 58.67 54.2592 57.07L58.0992 24.67C58.3092 22.57 57.2892 20.07 56.0792 18.37Z\" fill=\"#846834\"><\/path><path d=\"M28.1595 29.87C27.6495 28.67 26.2395 27.97 24.9195 28.17L26.3395 24.57C26.9495 22.87 25.9395 20.97 24.1095 20.57C24.7195 17.57 20.7695 15.67 18.8495 18.07C17.4295 17.17 15.4095 17.67 14.5995 19.07C12.9795 18.17 10.8595 18.87 10.2495 20.57L5.90953 31.87C5.29953 33.57 5.60953 35.57 6.61953 36.97L5.80953 38.97C5.19953 40.47 7.62953 41.37 8.13953 39.87L9.14953 37.17C9.44953 36.27 8.63953 35.77 8.33953 35.07C8.03953 34.37 7.93953 33.47 8.23953 32.77L12.5895 21.47C12.7895 20.87 13.6995 21.27 13.4995 21.77L12.1795 25.27C11.5695 26.77 13.9995 27.67 14.4995 26.17L15.8195 22.67L16.7295 20.37C16.9295 19.77 17.8395 20.17 17.6395 20.67L16.3195 24.17C15.7095 25.67 18.1395 26.57 18.6495 25.07L19.9695 21.57L20.6795 19.77C20.8795 19.17 21.7895 19.57 21.5895 20.07L20.6795 22.37L19.3695 25.87C18.7595 27.37 21.1895 28.27 21.6995 26.77L22.9995 23.27C23.1995 22.67 24.1095 23.07 23.9095 23.57L21.2795 30.47C20.8795 31.57 22.1895 32.67 23.1995 31.97L25.2195 30.57C25.5195 30.47 25.8295 30.67 25.8295 31.07C25.8295 31.47 25.5295 31.47 25.2195 31.67L18.8495 36.97C18.2395 37.47 17.9395 38.07 17.2295 38.37C16.5195 38.67 15.5095 38.47 15.2095 39.37L14.1995 42.07C13.8995 42.77 14.4995 43.47 14.7095 44.07C15.2195 45.17 15.5195 46.27 15.8195 47.37C16.2195 48.87 16.4295 50.37 16.3295 51.97C16.3295 52.77 16.2295 53.57 15.9295 54.37C15.7295 55.17 15.0195 56.07 15.0195 56.87C15.0195 57.67 15.9295 58.27 16.7395 57.97C17.5495 57.67 17.8495 56.57 18.1595 55.87C18.7695 54.07 18.9695 52.17 18.8695 50.27C18.6695 47.57 17.8595 44.87 16.6395 42.47L17.2495 40.97C18.5595 40.67 19.7795 39.87 20.5895 38.77L26.7595 33.67C28.1595 32.97 28.7695 31.27 28.1595 29.87C28.7695 31.27 27.7595 29.07 28.1595 29.87Z\" fill=\"#846834\"><\/path><path d=\"M50.7201 46.27C51.8301 44.87 52.1401 42.77 51.4301 40.97L46.9801 29.47C46.7801 28.37 46.6801 27.27 46.8801 26.17C46.9801 25.27 47.1801 24.37 47.5901 23.47C47.7901 22.97 48.1001 22.57 48.4001 22.17C48.7001 21.77 49.1101 21.47 49.2101 20.97C49.4101 20.07 48.5001 19.27 47.5901 19.57C46.6801 19.87 45.9701 21.27 45.5701 22.07C44.6601 23.77 44.2601 25.67 44.2601 27.57C43.6501 27.57 43.0501 27.67 42.5401 27.97C41.7301 26.47 39.6101 25.97 38.1901 26.87C36.2701 24.37 32.1201 26.37 32.8301 29.37C31.0101 29.67 29.8001 31.67 30.5001 33.47L31.9201 37.27C28.5801 36.67 26.9601 41.37 30.0001 42.97L36.3701 48.27C37.1801 49.37 38.4901 50.27 39.8101 50.57L40.5201 52.47V56.97C40.5201 58.57 43.0501 58.57 43.0501 56.97V52.17C43.0501 51.97 43.0501 51.87 42.9501 51.77L41.8401 48.97C41.5401 48.07 40.5201 48.27 39.8201 47.97C39.0101 47.67 38.7101 46.97 38.0001 46.47L31.4201 40.97C31.2201 40.77 30.8101 40.67 30.8101 40.37C30.8101 39.97 31.1101 39.77 31.5201 39.87L33.6401 41.27C34.6501 41.97 35.9701 40.87 35.5601 39.77L32.8301 32.67C32.6301 32.07 33.6401 31.67 33.8401 32.27L35.2601 35.87C35.8701 37.37 38.1901 36.47 37.5901 34.97L36.1701 31.37L35.1601 28.97C34.9601 28.37 35.9701 27.97 36.1701 28.57L36.8801 30.47L38.3001 34.07C38.9101 35.57 41.2301 34.67 40.6301 33.17L39.2101 29.57C38.9101 28.97 40.0201 28.57 40.2201 29.17L41.1301 31.57L42.5501 35.17C43.1601 36.67 45.4801 35.77 44.8801 34.27L43.4601 30.67C43.2601 30.07 44.2701 29.67 44.4701 30.27L48.9201 41.87C49.2201 42.67 49.1201 43.57 48.8201 44.27C48.5201 44.97 47.6101 45.47 47.9101 46.37L49.0001 49.17C49.6101 50.67 51.9301 49.77 51.3301 48.27L50.7201 46.27Z\" fill=\"#846834\"><\/path><\/g><defs><clipPath id=\"clip0_478_550\"><rect width=\"58.13\" height=\"57.46\" fill=\"white\" transform=\"translate(0 0.77002)\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"59\" height=\"59\" viewBox=\"0 0 59 59\" fill=\"none\"><g clip-path=\"url(#clip0_478_550)\"><path d=\"M2.37017 24.47C2.37017 22.07 3.58017 19.67 5.61017 18.17C6.62017 17.47 7.84017 16.87 9.15017 16.77C10.4602 16.67 11.6802 16.57 12.9902 16.17C17.7402 14.67 21.0802 10.17 21.0802 5.27002V1.97002C21.0802 0.37002 18.5502 0.37002 18.5502 1.97002V5.27002C18.5502 9.87002 14.8102 13.87 10.1502 14.27C8.84017 14.37 7.62017 14.47 6.31017 14.97C5.10017 15.47 3.98017 16.27 3.07017 17.17C1.25017 19.07 -0.269826 22.07 0.0301736 24.77L3.87017 57.17C4.07017 58.77 6.60017 58.47 6.40017 56.87L2.37017 24.47Z\" fill=\"#846834\"><\/path><path d=\"M56.0792 18.37C54.8692 16.77 53.1492 15.47 51.2192 14.77C49.2992 14.07 47.2692 14.37 45.3492 13.67C41.9092 12.37 39.4792 8.97002 39.4792 5.27002V1.97002C39.4792 0.37002 36.9492 0.37002 36.9492 1.97002V5.27002C36.9492 10.07 40.1892 14.57 44.7392 16.17C45.8492 16.57 47.0692 16.77 48.2792 16.77C49.6992 16.77 50.9092 17.27 52.0192 18.07C54.1392 19.57 55.3592 21.97 55.3592 24.47L51.7292 56.77C51.5292 58.37 54.0592 58.67 54.2592 57.07L58.0992 24.67C58.3092 22.57 57.2892 20.07 56.0792 18.37Z\" fill=\"#846834\"><\/path><path d=\"M28.1595 29.87C27.6495 28.67 26.2395 27.97 24.9195 28.17L26.3395 24.57C26.9495 22.87 25.9395 20.97 24.1095 20.57C24.7195 17.57 20.7695 15.67 18.8495 18.07C17.4295 17.17 15.4095 17.67 14.5995 19.07C12.9795 18.17 10.8595 18.87 10.2495 20.57L5.90953 31.87C5.29953 33.57 5.60953 35.57 6.61953 36.97L5.80953 38.97C5.19953 40.47 7.62953 41.37 8.13953 39.87L9.14953 37.17C9.44953 36.27 8.63953 35.77 8.33953 35.07C8.03953 34.37 7.93953 33.47 8.23953 32.77L12.5895 21.47C12.7895 20.87 13.6995 21.27 13.4995 21.77L12.1795 25.27C11.5695 26.77 13.9995 27.67 14.4995 26.17L15.8195 22.67L16.7295 20.37C16.9295 19.77 17.8395 20.17 17.6395 20.67L16.3195 24.17C15.7095 25.67 18.1395 26.57 18.6495 25.07L19.9695 21.57L20.6795 19.77C20.8795 19.17 21.7895 19.57 21.5895 20.07L20.6795 22.37L19.3695 25.87C18.7595 27.37 21.1895 28.27 21.6995 26.77L22.9995 23.27C23.1995 22.67 24.1095 23.07 23.9095 23.57L21.2795 30.47C20.8795 31.57 22.1895 32.67 23.1995 31.97L25.2195 30.57C25.5195 30.47 25.8295 30.67 25.8295 31.07C25.8295 31.47 25.5295 31.47 25.2195 31.67L18.8495 36.97C18.2395 37.47 17.9395 38.07 17.2295 38.37C16.5195 38.67 15.5095 38.47 15.2095 39.37L14.1995 42.07C13.8995 42.77 14.4995 43.47 14.7095 44.07C15.2195 45.17 15.5195 46.27 15.8195 47.37C16.2195 48.87 16.4295 50.37 16.3295 51.97C16.3295 52.77 16.2295 53.57 15.9295 54.37C15.7295 55.17 15.0195 56.07 15.0195 56.87C15.0195 57.67 15.9295 58.27 16.7395 57.97C17.5495 57.67 17.8495 56.57 18.1595 55.87C18.7695 54.07 18.9695 52.17 18.8695 50.27C18.6695 47.57 17.8595 44.87 16.6395 42.47L17.2495 40.97C18.5595 40.67 19.7795 39.87 20.5895 38.77L26.7595 33.67C28.1595 32.97 28.7695 31.27 28.1595 29.87C28.7695 31.27 27.7595 29.07 28.1595 29.87Z\" fill=\"#846834\"><\/path><path d=\"M50.7201 46.27C51.8301 44.87 52.1401 42.77 51.4301 40.97L46.9801 29.47C46.7801 28.37 46.6801 27.27 46.8801 26.17C46.9801 25.27 47.1801 24.37 47.5901 23.47C47.7901 22.97 48.1001 22.57 48.4001 22.17C48.7001 21.77 49.1101 21.47 49.2101 20.97C49.4101 20.07 48.5001 19.27 47.5901 19.57C46.6801 19.87 45.9701 21.27 45.5701 22.07C44.6601 23.77 44.2601 25.67 44.2601 27.57C43.6501 27.57 43.0501 27.67 42.5401 27.97C41.7301 26.47 39.6101 25.97 38.1901 26.87C36.2701 24.37 32.1201 26.37 32.8301 29.37C31.0101 29.67 29.8001 31.67 30.5001 33.47L31.9201 37.27C28.5801 36.67 26.9601 41.37 30.0001 42.97L36.3701 48.27C37.1801 49.37 38.4901 50.27 39.8101 50.57L40.5201 52.47V56.97C40.5201 58.57 43.0501 58.57 43.0501 56.97V52.17C43.0501 51.97 43.0501 51.87 42.9501 51.77L41.8401 48.97C41.5401 48.07 40.5201 48.27 39.8201 47.97C39.0101 47.67 38.7101 46.97 38.0001 46.47L31.4201 40.97C31.2201 40.77 30.8101 40.67 30.8101 40.37C30.8101 39.97 31.1101 39.77 31.5201 39.87L33.6401 41.27C34.6501 41.97 35.9701 40.87 35.5601 39.77L32.8301 32.67C32.6301 32.07 33.6401 31.67 33.8401 32.27L35.2601 35.87C35.8701 37.37 38.1901 36.47 37.5901 34.97L36.1701 31.37L35.1601 28.97C34.9601 28.37 35.9701 27.97 36.1701 28.57L36.8801 30.47L38.3001 34.07C38.9101 35.57 41.2301 34.67 40.6301 33.17L39.2101 29.57C38.9101 28.97 40.0201 28.57 40.2201 29.17L41.1301 31.57L42.5501 35.17C43.1601 36.67 45.4801 35.77 44.8801 34.27L43.4601 30.67C43.2601 30.07 44.2701 29.67 44.4701 30.27L48.9201 41.87C49.2201 42.67 49.1201 43.57 48.8201 44.27C48.5201 44.97 47.6101 45.47 47.9101 46.37L49.0001 49.17C49.6101 50.67 51.9301 49.77 51.3301 48.27L50.7201 46.27Z\" fill=\"#846834\"><\/path><\/g><defs><clipPath id=\"clip0_478_550\"><rect width=\"58.13\" height=\"57.46\" fill=\"white\" transform=\"translate(0 0.77002)\"><\/rect><\/clipPath><\/defs><\/svg>\t\t<\/span>\n\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tRelax and Enjoy\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div id=\"e-n-tab-content-309153891\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-309153891\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-9d33360 e-con-full e-flex e-con e-child\" data-id=\"9d33360\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d435c9d elementor-widget elementor-widget-image\" data-id=\"d435c9d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"432\" src=\"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/sign-up-tab-1.webp\" class=\"attachment-full size-full wp-image-1572\" alt=\"\" srcset=\"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/sign-up-tab-1.webp 600w, https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/sign-up-tab-1-300x216.webp 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-309153892\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-309153892\" data-tab-index=\"2\" style=\"--n-tabs-title-order: 2;\" class=\" elementor-element elementor-element-661b91e e-con-full e-flex e-con e-child\" data-id=\"661b91e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f786428 elementor-widget elementor-widget-image\" data-id=\"f786428\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"1024\" src=\"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/Psychic-Guidance.png\" class=\"attachment-full size-full wp-image-1449\" alt=\"\" srcset=\"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/Psychic-Guidance.png 1536w, https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/Psychic-Guidance-300x200.png 300w, https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/Psychic-Guidance-1024x683.png 1024w, https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/Psychic-Guidance-768x512.png 768w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-309153893\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-309153893\" data-tab-index=\"3\" style=\"--n-tabs-title-order: 3;\" class=\" elementor-element elementor-element-5d3a13a e-con-full e-flex e-con e-child\" data-id=\"5d3a13a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6402380 elementor-widget elementor-widget-image\" data-id=\"6402380\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/Tarot-Readings-1.jpg\" class=\"attachment-full size-full wp-image-1405\" alt=\"\" srcset=\"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/Tarot-Readings-1.jpg 640w, https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/Tarot-Readings-1-300x200.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7b96b5f e-flex e-con-boxed e-con e-parent\" data-id=\"7b96b5f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1be6c3d elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"1be6c3d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Membership Terms\n at a Glance<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d91361 elementor-widget elementor-widget-image\" data-id=\"6d91361\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"230\" height=\"18\" src=\"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/10\/sec-shape-1-1.png\" class=\"attachment-medium size-medium wp-image-2985\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7eee601 e-con-full e-flex e-con e-child\" data-id=\"7eee601\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e3f467e e-con-full e-flex e-con e-child\" data-id=\"e3f467e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a7dd427 elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a7dd427\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Enjoy a 60-minute classic massage or facial every month, your personal time to relax, refresh, and recharge. Plus, indulge in as many extra classic massages and\/or facials as you\u2019d like with 15% off all month long. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">10% off all retail products\u00a0\u2013 stock up on self-care essentials.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">No long-term commitment\u00a0\u2013 stay flexible on your wellness journey.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Easy online booking\u00a0\u2013 wellness at your fingertips<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-37db76e e-con-full e-flex e-con e-child\" data-id=\"37db76e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b588f1 elementor-widget elementor-widget-image\" data-id=\"1b588f1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"492\" height=\"607\" src=\"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/10\/Membership-Terms-img.webp\" class=\"attachment-full size-full wp-image-2986\" alt=\"\" srcset=\"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/10\/Membership-Terms-img.webp 492w, https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/10\/Membership-Terms-img-243x300.webp 243w\" sizes=\"(max-width: 492px) 100vw, 492px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-abc0110 e-con-full e-flex e-con e-child\" data-id=\"abc0110\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d37056c elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d37056c\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sessions can roll over for up to 6 months\u00a0\u2013 no pressure, just progress<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Share unused sessions with a friend or family member\u00a0\u2013 wellness is better together.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cancel appointments by 5 PM the day before to avoid loss\u00a0\u2013 respect your time and ours<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cancel membership with 30 days' written notice\u00a0\u2013 easy in, easy out<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Freeze membership once per 6-month period (up to 30 days)\u00a0\u2013 pause without penalty<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Join Our Wellness Membership Looking for a self-care routine you\u2019ll enjoy and actually stick to? Our Massage and Wellness Membership Progra is designed with you in mind. It\u2019s a totally stress free way to get stress free. Start your path to personal wellness today with routine therapeutic massage and skincare*. Member&#8217;s Special 60 Min 90 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-1539","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Memberships - Life Massage and Wellness in Amesbury, MA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lifemassageandwellness.com\/Amesbury\/memberships\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Memberships - Life Massage and Wellness in Amesbury, MA\" \/>\n<meta property=\"og:description\" content=\"Join Our Wellness Membership Looking for a self-care routine you\u2019ll enjoy and actually stick to? Our Massage and Wellness Membership Progra is designed with you in mind. It\u2019s a totally stress free way to get stress free. Start your path to personal wellness today with routine therapeutic massage and skincare*. Member&#8217;s Special 60 Min 90 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lifemassageandwellness.com\/Amesbury\/memberships\/\" \/>\n<meta property=\"og:site_name\" content=\"Life Massage and Wellness in Amesbury, MA\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-28T22:29:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/sec-shape-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"230\" \/>\n\t<meta property=\"og:image:height\" content=\"18\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lifemassageandwellness.com\/Amesbury\/memberships\/\",\"url\":\"https:\/\/lifemassageandwellness.com\/Amesbury\/memberships\/\",\"name\":\"Memberships - Life Massage and Wellness in Amesbury, MA\",\"isPartOf\":{\"@id\":\"https:\/\/lifemassageandwellness.com\/Amesbury\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/lifemassageandwellness.com\/Amesbury\/memberships\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/lifemassageandwellness.com\/Amesbury\/memberships\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/sec-shape-1.png\",\"datePublished\":\"2025-09-19T02:08:27+00:00\",\"dateModified\":\"2025-10-28T22:29:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/lifemassageandwellness.com\/Amesbury\/memberships\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lifemassageandwellness.com\/Amesbury\/memberships\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/lifemassageandwellness.com\/Amesbury\/memberships\/#primaryimage\",\"url\":\"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/sec-shape-1.png\",\"contentUrl\":\"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/sec-shape-1.png\",\"width\":230,\"height\":18},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lifemassageandwellness.com\/Amesbury\/memberships\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/lifemassageandwellness.com\/Amesbury\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Memberships\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lifemassageandwellness.com\/Amesbury\/#website\",\"url\":\"https:\/\/lifemassageandwellness.com\/Amesbury\/\",\"name\":\"Life Massage & Wellness\",\"description\":\"Life Massage &amp; Wellness in Amesbury, MA. Offering facials, massage &amp; holistic therapies in a sanctuary setting.\",\"publisher\":{\"@id\":\"https:\/\/lifemassageandwellness.com\/Amesbury\/#organization\"},\"alternateName\":\"Massage Therapy & Facials in Amesbury, MA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lifemassageandwellness.com\/Amesbury\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lifemassageandwellness.com\/Amesbury\/#organization\",\"name\":\"Massage & Wellness Collective\",\"url\":\"https:\/\/lifemassageandwellness.com\/Amesbury\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/lifemassageandwellness.com\/Amesbury\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Massage & Wellness Collective\"},\"image\":{\"@id\":\"https:\/\/lifemassageandwellness.com\/Amesbury\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/Massageandwellnesscollective\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Memberships - Life Massage and Wellness in Amesbury, MA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lifemassageandwellness.com\/Amesbury\/memberships\/","og_locale":"en_US","og_type":"article","og_title":"Memberships - Life Massage and Wellness in Amesbury, MA","og_description":"Join Our Wellness Membership Looking for a self-care routine you\u2019ll enjoy and actually stick to? Our Massage and Wellness Membership Progra is designed with you in mind. It\u2019s a totally stress free way to get stress free. Start your path to personal wellness today with routine therapeutic massage and skincare*. Member&#8217;s Special 60 Min 90 [&hellip;]","og_url":"https:\/\/lifemassageandwellness.com\/Amesbury\/memberships\/","og_site_name":"Life Massage and Wellness in Amesbury, MA","article_modified_time":"2025-10-28T22:29:02+00:00","og_image":[{"width":230,"height":18,"url":"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/sec-shape-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lifemassageandwellness.com\/Amesbury\/memberships\/","url":"https:\/\/lifemassageandwellness.com\/Amesbury\/memberships\/","name":"Memberships - Life Massage and Wellness in Amesbury, MA","isPartOf":{"@id":"https:\/\/lifemassageandwellness.com\/Amesbury\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lifemassageandwellness.com\/Amesbury\/memberships\/#primaryimage"},"image":{"@id":"https:\/\/lifemassageandwellness.com\/Amesbury\/memberships\/#primaryimage"},"thumbnailUrl":"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/sec-shape-1.png","datePublished":"2025-09-19T02:08:27+00:00","dateModified":"2025-10-28T22:29:02+00:00","breadcrumb":{"@id":"https:\/\/lifemassageandwellness.com\/Amesbury\/memberships\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lifemassageandwellness.com\/Amesbury\/memberships\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lifemassageandwellness.com\/Amesbury\/memberships\/#primaryimage","url":"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/sec-shape-1.png","contentUrl":"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-content\/uploads\/2025\/09\/sec-shape-1.png","width":230,"height":18},{"@type":"BreadcrumbList","@id":"https:\/\/lifemassageandwellness.com\/Amesbury\/memberships\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lifemassageandwellness.com\/Amesbury\/"},{"@type":"ListItem","position":2,"name":"Memberships"}]},{"@type":"WebSite","@id":"https:\/\/lifemassageandwellness.com\/Amesbury\/#website","url":"https:\/\/lifemassageandwellness.com\/Amesbury\/","name":"Life Massage & Wellness","description":"Life Massage &amp; Wellness in Amesbury, MA. Offering facials, massage &amp; holistic therapies in a sanctuary setting.","publisher":{"@id":"https:\/\/lifemassageandwellness.com\/Amesbury\/#organization"},"alternateName":"Massage Therapy & Facials in Amesbury, MA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lifemassageandwellness.com\/Amesbury\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lifemassageandwellness.com\/Amesbury\/#organization","name":"Massage & Wellness Collective","url":"https:\/\/lifemassageandwellness.com\/Amesbury\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lifemassageandwellness.com\/Amesbury\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Massage & Wellness Collective"},"image":{"@id":"https:\/\/lifemassageandwellness.com\/Amesbury\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/Massageandwellnesscollective"]}]}},"_links":{"self":[{"href":"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-json\/wp\/v2\/pages\/1539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-json\/wp\/v2\/comments?post=1539"}],"version-history":[{"count":94,"href":"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-json\/wp\/v2\/pages\/1539\/revisions"}],"predecessor-version":[{"id":3262,"href":"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-json\/wp\/v2\/pages\/1539\/revisions\/3262"}],"wp:attachment":[{"href":"https:\/\/lifemassageandwellness.com\/Amesbury\/wp-json\/wp\/v2\/media?parent=1539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}